{"id":888,"date":"2019-12-17T16:49:48","date_gmt":"2019-12-17T15:49:48","guid":{"rendered":"http:\/\/wp.hrexpert.de\/?p=888"},"modified":"2020-02-03T12:04:43","modified_gmt":"2020-02-03T11:04:43","slug":"ikk-classic","status":"publish","type":"post","link":"https:\/\/hrexpert.de\/en\/2019\/12\/17\/ikk-classic\/","title":{"rendered":"IKK Classic"},"content":{"rendered":"<p>HR Interim Management anl\u00e4sslich eines Re-Organisationsprojekts<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ausbau und Stabilisierung der Personalarbeit<\/li><li>Einf\u00fchrung eines HR Business Partner Modells<\/li><li>Optimierung der Zusammenarbeit mit <\/li><\/ul>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>HR Interim Management anl\u00e4sslich eines Re-Organisationsprojekts Ausbau und Stabilisierung der Personalarbeit Einf\u00fchrung eines HR Business Partner Modells Optimierung der Zusammenarbeit mit<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[8],"class_list":["post-888","post","type-post","status-publish","format-standard","hentry","category-referenz","tag-interim-manager"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"slider-image":false,"header-image":false,"ref-image":false,"icon":false},"uagb_author_info":{"display_name":"duf_admin","author_link":"https:\/\/hrexpert.de\/en\/author\/duf_admin\/"},"uagb_comment_info":0,"uagb_excerpt":"HR Interim Management anl\u00e4sslich eines Re-Organisationsprojekts Ausbau und Stabilisierung der Personalarbeit Einf\u00fchrung eines HR Business Partner Modells Optimierung der Zusammenarbeit mit","_links":{"self":[{"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/posts\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":2,"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/posts\/888\/revisions"}],"predecessor-version":[{"id":890,"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/posts\/888\/revisions\/890"}],"wp:attachment":[{"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/media?parent=888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/categories?post=888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hrexpert.de\/en\/wp-json\/wp\/v2\/tags?post=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}